{"id":22971,"count":1,"description":"","link":"https:\/\/www.jesstechnology.com\/th\/tag\/mp284-4-pcb-sewing-machine-pcb-board-repair-in-tebrau\/","name":"MP284-4 PCB SEWING MACHINE PCB BOARD repair in Tebrau","slug":"mp284-4-pcb-sewing-machine-pcb-board-repair-in-tebrau","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.jesstechnology.com\/th\/wp-json\/wp\/v2\/tags\/22971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jesstechnology.com\/th\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.jesstechnology.com\/th\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.jesstechnology.com\/th\/wp-json\/wp\/v2\/posts?tags=22971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}