{"id":1470983,"count":1,"description":"","link":"https:\/\/www.jesstechnology.com\/sg\/tag\/ad-4401-weighing-indicator-controller-brand-weighing-indicator-controller-model-ad-4401-s-n-k4450330-k4450330-repair-in-kulim\/","name":"AD-4401 WEIGHING INDICATOR CONTROLLER Brand : WEIGHING INDICATOR CONTROLLER Model : AD-4401 S\/N : K4450330 K4450330 repair in Kulim","slug":"ad-4401-weighing-indicator-controller-brand-weighing-indicator-controller-model-ad-4401-s-n-k4450330-k4450330-repair-in-kulim","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.jesstechnology.com\/sg\/wp-json\/wp\/v2\/tags\/1470983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jesstechnology.com\/sg\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.jesstechnology.com\/sg\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.jesstechnology.com\/sg\/wp-json\/wp\/v2\/posts?tags=1470983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}